{"id":1815,"date":"2008-12-07T13:06:10","date_gmt":"2008-12-07T12:06:10","guid":{"rendered":"http:\/\/www.glorf.it\/blog\/?p=1815"},"modified":"2008-12-05T13:07:43","modified_gmt":"2008-12-05T12:07:43","slug":"vorstellungsgespraeche-frueher","status":"publish","type":"post","link":"http:\/\/www.glorf.it\/blog\/2008\/12\/07\/offtopic\/vorstellungsgespraeche-frueher","title":{"rendered":"Vorstellungsgespr&#228;che fr&#252;her"},"content":{"rendered":"<p>Fr&#252;her waren die Zeiten in mancher Hinsicht einfacher und in mancher Hinsicht h&#228;rter. Aber seht selbst:<\/p>\n<p><object width=\"425\" height=\"344\"><param name=\"movie\" value=\"http:\/\/www.youtube.com\/v\/zP0sqRMzkwo&#038;color1=0xb1b1b1&#038;color2=0xcfcfcf&#038;hl=de&#038;feature=player_embedded&#038;fs=1\"><\/param><param name=\"allowFullScreen\" value=\"true\"><\/param><embed src=\"http:\/\/www.youtube.com\/v\/zP0sqRMzkwo&#038;color1=0xb1b1b1&#038;color2=0xcfcfcf&#038;hl=de&#038;feature=player_embedded&#038;fs=1\" type=\"application\/x-shockwave-flash\" allowfullscreen=\"true\" width=\"425\" height=\"344\"><\/embed><\/object><\/p>\n<p>&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fr&#252;her waren die Zeiten in mancher Hinsicht einfacher und in mancher Hinsicht h&#228;rter. Aber seht selbst: &#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[9],"tags":[218],"_links":{"self":[{"href":"http:\/\/www.glorf.it\/blog\/wp-json\/wp\/v2\/posts\/1815"}],"collection":[{"href":"http:\/\/www.glorf.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.glorf.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.glorf.it\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.glorf.it\/blog\/wp-json\/wp\/v2\/comments?post=1815"}],"version-history":[{"count":1,"href":"http:\/\/www.glorf.it\/blog\/wp-json\/wp\/v2\/posts\/1815\/revisions"}],"predecessor-version":[{"id":1816,"href":"http:\/\/www.glorf.it\/blog\/wp-json\/wp\/v2\/posts\/1815\/revisions\/1816"}],"wp:attachment":[{"href":"http:\/\/www.glorf.it\/blog\/wp-json\/wp\/v2\/media?parent=1815"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.glorf.it\/blog\/wp-json\/wp\/v2\/categories?post=1815"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.glorf.it\/blog\/wp-json\/wp\/v2\/tags?post=1815"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}