{"id":253,"date":"2006-11-03T18:59:44","date_gmt":"2006-11-03T16:59:44","guid":{"rendered":"http:\/\/www.glorf.it\/blog\/2006\/11\/03\/webtech\/jubilaeum-der-1000te-spam-kommentar"},"modified":"2006-11-03T18:59:44","modified_gmt":"2006-11-03T16:59:44","slug":"jubilaeum-der-1000te-spam-kommentar","status":"publish","type":"post","link":"http:\/\/www.glorf.it\/blog\/2006\/11\/03\/webtech\/jubilaeum-der-1000te-spam-kommentar","title":{"rendered":"Jubil&#228;um: Der 1000te SPAM-Kommentar"},"content":{"rendered":"<p>Heute feiert dieser Blog ein ganz besonderes Jubil&#228;um: Die 1000er Marke wurde &#252;berschritten&#8230;<br \/>\nNun habe ich also tats&#228;chlich mehr als 1000 SPAM-Kommentare bekommen. Ist das ein Grund zum Jubeln? Nein, aber das mein Spamfilter &quot;<a href=\"http:\/\/akismet.com\/\" target=\"_blank\">Akismet<\/a>&quot; sie (bis auf 2) alle rausgefangen hat!<\/p>\n<p><span style=\"font-size: large\"><a href=\"http:\/\/akismet.com\/\" target=\"_blank\">Danke Akismet!<\/a><\/span><\/p>\n<p>Der 1000te wurde &#252;brigens von der IP-Adresse <a href=\"http:\/\/ws.arin.net\/cgi-bin\/whois.pl?queryinput=211.138.198.7\" target=\"_blank\">211.138.198.7<\/a> eingeschickt und warb f&#252;r eine polnische Seite &#252;belsten Kalibers.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Heute feiert dieser Blog ein ganz besonderes Jubil&#228;um: Die 1000er Marke wurde &#252;berschritten&#8230; Nun habe ich also tats&#228;chlich mehr als 1000 SPAM-Kommentare bekommen. Ist das ein Grund zum Jubeln? Nein, aber das mein Spamfilter &quot;Akismet&quot; sie (bis auf 2) alle rausgefangen hat! Danke Akismet! Der 1000te wurde &#252;brigens von der IP-Adresse 211.138.198.7 eingeschickt und warb [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[2],"tags":[],"_links":{"self":[{"href":"http:\/\/www.glorf.it\/blog\/wp-json\/wp\/v2\/posts\/253"}],"collection":[{"href":"http:\/\/www.glorf.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.glorf.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.glorf.it\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.glorf.it\/blog\/wp-json\/wp\/v2\/comments?post=253"}],"version-history":[{"count":0,"href":"http:\/\/www.glorf.it\/blog\/wp-json\/wp\/v2\/posts\/253\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.glorf.it\/blog\/wp-json\/wp\/v2\/media?parent=253"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.glorf.it\/blog\/wp-json\/wp\/v2\/categories?post=253"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.glorf.it\/blog\/wp-json\/wp\/v2\/tags?post=253"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}