{"id":579,"date":"2007-05-22T23:27:15","date_gmt":"2007-05-22T21:27:15","guid":{"rendered":"http:\/\/www.glorf.it\/blog\/2007\/05\/22\/links\/und-ein-weiterer-team-blog-der-ms-sql-entwickler"},"modified":"2007-05-22T23:27:15","modified_gmt":"2007-05-22T21:27:15","slug":"und-ein-weiterer-team-blog-der-ms-sql-entwickler","status":"publish","type":"post","link":"http:\/\/www.glorf.it\/blog\/2007\/05\/22\/links\/und-ein-weiterer-team-blog-der-ms-sql-entwickler","title":{"rendered":"und ein weiterer Team-Blog der MS-SQL-Entwickler"},"content":{"rendered":"<p>Heute habe ich den &quot;<a href=\"http:\/\/blogs.msdn.com\/sqlprogrammability\/\">SQL Programmability &#038; API Development Team Blog<\/a>&quot; f&#252;r mich entdeckt. Er enth&#228;lt jede Menge detaillierter Informationen &#252;ber potentielle Performance-Probleme, &#252;ber Zugriffspl&#228;ne, Cache-Nutzung, usw. am SQL-Server-2005.<\/p>\n<p>Es wird lange dauern bis ich die Artikel durchgearbeitet habe! Alle erste Klasse! \ud83d\ude09 <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Heute habe ich den &quot;SQL Programmability &#038; API Development Team Blog&quot; f&#252;r mich entdeckt. Er enth&#228;lt jede Menge detaillierter Informationen &#252;ber potentielle Performance-Probleme, &#252;ber Zugriffspl&#228;ne, Cache-Nutzung, usw. am SQL-Server-2005. Es wird lange dauern bis ich die Artikel durchgearbeitet habe! Alle erste Klasse! \ud83d\ude09<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[12,16],"tags":[],"_links":{"self":[{"href":"http:\/\/www.glorf.it\/blog\/wp-json\/wp\/v2\/posts\/579"}],"collection":[{"href":"http:\/\/www.glorf.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.glorf.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.glorf.it\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.glorf.it\/blog\/wp-json\/wp\/v2\/comments?post=579"}],"version-history":[{"count":0,"href":"http:\/\/www.glorf.it\/blog\/wp-json\/wp\/v2\/posts\/579\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.glorf.it\/blog\/wp-json\/wp\/v2\/media?parent=579"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.glorf.it\/blog\/wp-json\/wp\/v2\/categories?post=579"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.glorf.it\/blog\/wp-json\/wp\/v2\/tags?post=579"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}