{"id":6088,"date":"2011-05-14T12:13:40","date_gmt":"2011-05-14T10:13:40","guid":{"rendered":"http:\/\/www.glorf.it\/blog\/?p=6088"},"modified":"2011-05-14T12:13:40","modified_gmt":"2011-05-14T10:13:40","slug":"wie-viel-darf-sicherheit-kosten","status":"publish","type":"post","link":"http:\/\/www.glorf.it\/blog\/2011\/05\/14\/security\/wie-viel-darf-sicherheit-kosten","title":{"rendered":"Wie viel darf Sicherheit kosten?"},"content":{"rendered":"<p>Auf die Frage wie viel man f&#252;r die Sicherheit ausgeben darf gibt es offenbar keine richtige Antwort: &quot;so viel wie n&#246;tig&quot; ist eben auch nicht wirklich hilfreich. Daher hat mich der Spiegel-Artikel &quot;<a href=\"http:\/\/www.spiegel.de\/wissenschaft\/technik\/0,1518,762341,00.html\">Umstrittenes Bauwerk &#8211; Riesenmauer rettete japanisches Dorf vor Tsunami<\/a>&quot; schon beeindruckt. Gegen viele Widerst&#228;nde dr&#252;ckte ein B&#252;rgermeister ein riesen Bauwerk durch, was sich so gerade als gro&#223; genug entpuppte.<\/p>\n<p>Der letzte Satz <a href=\"http:\/\/www.spiegel.de\/wissenschaft\/technik\/0,1518,762341,00.html\">des Artikels<\/a> hat mich ber&#252;hrt:<\/p>\n<blockquote><p>&quot;Auch wenn es Widerstand gibt, habt Vertrauen und beendet, was Ihr begonnen habt&quot;, sagte er bei seiner Verabschiedung zu den Angestellten. &quot;Am Ende werden die Leute verstehen.&quot;<\/p><\/blockquote>\n<p>Lange nach seinem Tod ist er pl&#246;tzlich der Held der Stadt. Hier kann man <a href=\"http:\/\/maps.google.de\/maps?hl=de&#038;safe=off&#038;q=fudai,+japan&#038;ie=UTF8&#038;hq=&#038;hnear=Fudai,+Shimohei+District,+Pr%C3%A4fektur+Iwate,+Japan&#038;ll=40.012201,141.894071&#038;spn=0.012408,0.01929&#038;t=h&#038;z=16\">die erw&#228;hnte Mauer<\/a> sehen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Auf die Frage wie viel man f&#252;r die Sicherheit ausgeben darf gibt es offenbar keine richtige Antwort: &quot;so viel wie n&#246;tig&quot; ist eben auch nicht wirklich hilfreich. Daher hat mich der Spiegel-Artikel &quot;Umstrittenes Bauwerk &#8211; Riesenmauer rettete japanisches Dorf vor Tsunami&quot; schon beeindruckt. Gegen viele Widerst&#228;nde dr&#252;ckte ein B&#252;rgermeister ein riesen Bauwerk durch, was sich [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[19],"tags":[840,128],"_links":{"self":[{"href":"http:\/\/www.glorf.it\/blog\/wp-json\/wp\/v2\/posts\/6088"}],"collection":[{"href":"http:\/\/www.glorf.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.glorf.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.glorf.it\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.glorf.it\/blog\/wp-json\/wp\/v2\/comments?post=6088"}],"version-history":[{"count":3,"href":"http:\/\/www.glorf.it\/blog\/wp-json\/wp\/v2\/posts\/6088\/revisions"}],"predecessor-version":[{"id":6091,"href":"http:\/\/www.glorf.it\/blog\/wp-json\/wp\/v2\/posts\/6088\/revisions\/6091"}],"wp:attachment":[{"href":"http:\/\/www.glorf.it\/blog\/wp-json\/wp\/v2\/media?parent=6088"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.glorf.it\/blog\/wp-json\/wp\/v2\/categories?post=6088"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.glorf.it\/blog\/wp-json\/wp\/v2\/tags?post=6088"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}